{"id":5468,"count":12,"description":"","link":"https:\/\/woo.mair-mair.de\/de\/brand\/molino-pellegrini\/","name":"Molino Pellegrini","slug":"molino-pellegrini","taxonomy":"brand","meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/woo.mair-mair.de\/de\/wp-json\/wp\/v2\/brand\/5468","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/woo.mair-mair.de\/de\/wp-json\/wp\/v2\/brand"}],"about":[{"href":"https:\/\/woo.mair-mair.de\/de\/wp-json\/wp\/v2\/taxonomies\/brand"}],"wp:post_type":[{"href":"https:\/\/woo.mair-mair.de\/de\/wp-json\/wp\/v2\/product?brand=5468"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}